{"id":2322,"date":"2022-12-12T20:23:00","date_gmt":"2022-12-12T20:23:00","guid":{"rendered":"https:\/\/academiapoker.net\/escuela\/manos-poker\/"},"modified":"2023-02-03T14:58:23","modified_gmt":"2023-02-03T14:58:23","slug":"manos-poker","status":"publish","type":"post","link":"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/","title":{"rendered":"Secuencia de manos de p\u00f3ker"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el p\u00f3ker es fundamental conocer las diferentes combinaciones de todas las manos existentes. Conocer la secuencia de combinaciones le permite al jugador saber si arriesgar la mano, entrando en una ronda o aumentando la apuesta, y tambi\u00e9n cu\u00e1ndo retirarse. <\/p>\n\n<p class=\"wp-block-paragraph\">En la mayor\u00eda de los juegos, las combinaciones de manos de p\u00f3ker se componen de cinco cartas, contando las cartas de la mesa, o comunitarias, y las cartas de la mano. La excepci\u00f3n a esta regla se aplica solo a los juegos de Poker Badugi, que se componen de cuatro combinaciones de cartas. <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"550\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker.jpg\" alt=\"secuencia manos poker\" class=\"wp-image-802\" title=\"ranking manos poker\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker-300x206.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker-768x528.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Dependiendo del juego de p\u00f3ker, ser\u00e1 el tipo de ranking de manos. Los tipos de rankings que veremos aqu\u00ed son: Traditional High, Ace to Five Lowball, Deuce to Seven Lowball y el ranking de manos de Poker Badugi. <\/p>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenido:<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a57a5e0c2228\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #ffffff;color:#ffffff\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #ffffff;color:#ffffff\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a57a5e0c2228\" checked aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Conoce-las-manos-de-poker\" >Conoce las manos de p\u00f3ker<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Ranking-de-cartas-de-poker-%E2%80%9CTraditional-High%E2%80%9D\" >Ranking de cartas de p\u00f3ker &#8220;Traditional High&#8221;<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Escalera-Real\" >Escalera Real<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Escalera-de-Color\" >Escalera de Color<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Poker\" >P\u00f3ker<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Full\" >Full<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Color\" >Color<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Escalera\" >Escalera<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Tercia\" >Tercia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Doble-Pareja\" >Doble Pareja<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Pareja\" >Pareja<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Carta-Mas-Alta\" >Carta M\u00e1s Alta<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Orden-de-manos-de-poker-%E2%80%9CAce-to-Five%E2%80%9D-California\" >Orden de manos de p\u00f3ker &#8220;Ace to Five&#8221; (California)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Five-Low-o-Wheels\" >Five Low (o Wheels)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Six-Low\" >Six Low<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Seven-Low\" >Seven Low<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Eight-Low\" >Eight Low<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Ranking-de-cartas-de-poker-%E2%80%9CDeuce-to-Seven%E2%80%9D-Kansas-City\" >Ranking de cartas de p\u00f3ker &#8220;Deuce to Seven&#8221; (Kansas City)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Seven-Low-2\" >Seven Low<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Eight-Low-2\" >Eight Low<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Nine-Low\" >Nine Low<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Ten-Low\" >Ten Low<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Puntuacion-de-manos-de-poker-%E2%80%9CBadugi%E2%80%9D\" >Puntuaci\u00f3n de manos de p\u00f3ker &#8220;Badugi&#8221;<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Badugi\" >Badugi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Three-Card-Hand\" >Three-Card Hand<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Two-Card-Hand\" >Two-Card Hand<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#One-Card-Hand\" >One-Card Hand<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#%C2%BFCuales-son-las-mejores-manos-de-poker\" >\u00bfCu\u00e1les son las mejores manos de p\u00f3ker?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Nombres-populares-de-manos-de-poker\" >Nombres populares de manos de p\u00f3ker<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#TNT-o-TT\" >TNT (o TT)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Maverick\" >Maverick<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-32\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Ronaldo\" >Ronaldo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-33\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Rockets\" >Rockets<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-34\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Gutshot\" >Gutshot<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-35\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Kojak\" >Kojak<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-36\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Wheel\" >Wheel<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-37\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Backdoor\" >Backdoor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-38\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Valentines\" >Valentines<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-39\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Munecos-de-Nieve\" >Mu\u00f1ecos de Nieve<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-40\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Jacks\" >Jacks<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-41\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Phil-Hellmuth\" >Phil Hellmuth<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-42\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Dead-Mans-Hand\" >Dead Man&#8217;s Hand<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-43\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#King-Kong\" >King Kong<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-44\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Open-Ended\" >Open Ended<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-45\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Doyle-Brunson\" >Doyle Brunson<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-46\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Big-Slick\" >Big Slick<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-47\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#%C2%BFComo-es-el-desempate-en-el-poker\" >\u00bfC\u00f3mo es el desempate en el p\u00f3ker?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-48\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Conclusion\" >Conclusi\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-49\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#Preguntas-relacionadas\" >Preguntas relacionadas<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-50\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#%C2%BFCual-es-la-mano-mas-fuerte-en-el-poker\" >\u00bfCu\u00e1l es la mano m\u00e1s fuerte en el p\u00f3ker?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-51\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#%C2%BFQue-palo-vale-mas-en-el-poker\" >\u00bfQu\u00e9 palo vale m\u00e1s en el p\u00f3ker?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-52\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#%C2%BFCual-es-la-mano-mas-debil-en-el-poker\" >\u00bfCu\u00e1l es la mano m\u00e1s d\u00e9bil en el p\u00f3ker?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-53\" href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/#%C2%BFPor-que-dar-a-las-manos-de-poker-nombres-especiales-o-%E2%80%9Capodos%E2%80%9D\" >\u00bfPor qu\u00e9 dar a las manos de p\u00f3ker nombres especiales o &#8220;apodos&#8221;?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conoce-las-manos-de-poker\"><\/span>Conoce las manos de p\u00f3ker<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<div class=\"inherit-container-width wp-block-group has-ast-global-color-4-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--50)\">\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ranking-de-cartas-de-poker-%E2%80%9CTraditional-High%E2%80%9D\"><\/span><a><\/a>Ranking de cartas de p\u00f3ker &#8220;Traditional High&#8221;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La secuencia de cartas de p\u00f3ker Traditional High consta de cinco cartas y se aplica a los siguientes juegos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/academiapoker.net\/es-cl\/tipos-poker\/como-jugar-texas-holdem\/\">Hold&#8217;Em<\/a>: aqu\u00ed los jugadores reciben dos cartas en su mano, cerradas, y se reparten cinco cartas comunitarias. Los jugadores deben formar una combinaci\u00f3n de cinco cartas usando las dos de la mano y las cinco de la mesa. <\/li>\n\n\n\n<li><a href=\"https:\/\/academiapoker.net\/es-cl\/tipos-poker\/como-jugar-omaha\/\">Omaha<\/a>: el juego es similar al Hold&#8217;Em, con la diferencia de que los jugadores reciben cuatro cartas en su mano y no dos. Deben usar dos cartas de la mano y tres de la mesa para formar una mano. <\/li>\n\n\n\n<li><a href=\"https:\/\/academiapoker.net\/es-cl\/tipos-poker\/como-jugar-seven-card-stud\/\">Seven Card Stud<\/a>: en esta modalidad de juego, los jugadores reciben siete cartas cada uno, cuatro abiertas y tres cerradas, y no hay cartas comunitarias. Para formar una combinaci\u00f3n, cada jugador debe usar cinco cartas de las siete recibidas. <\/li>\n\n\n\n<li>Five Card Draw: este es un juego de p\u00f3ker cerrado, donde los jugadores reciben cinco cartas cerradas en su mano y pueden cambiar cartas entre rondas de apuestas.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Veamos las combinaciones de Traditional High desde la mano m\u00e1s alta hasta la m\u00e1s baja.<\/p>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-9cf2d968 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top fondo-blanco sombra-caja\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><span class=\"ez-toc-section\" id=\"Escalera-Real\"><\/span>Escalera Real<span class=\"ez-toc-section-end\"><\/span><\/h3><\/div><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/escalera-real-academia-poker.jpg\" alt=\"escalera real academia poker\" width=\"\" height=\"0\" loading=\"lazy\" title=\"Academia Poker\"><\/div><p class=\"uagb-ifb-desc\">Se compone de cinco cartas del mismo palo, desde el 10 hasta el As.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-2b6734d6 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top fondo-blanco sombra-caja\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><span class=\"ez-toc-section\" id=\"Escalera-de-Color\"><\/span>Escalera de Color<span class=\"ez-toc-section-end\"><\/span><\/h3><\/div><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/escalera-color-academia-poker.jpg\" alt=\"escalera color academia poker\" width=\"\" height=\"0\" loading=\"lazy\" title=\"Academia Poker\"><\/div><p class=\"uagb-ifb-desc\">Es una combinaci\u00f3n de cinco cartas en secuencia, del mismo palo.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-ddcb493f uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top fondo-blanco sombra-caja\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><span class=\"ez-toc-section\" id=\"Poker\"><\/span>P\u00f3ker<span class=\"ez-toc-section-end\"><\/span><\/h3><\/div><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/poker-academia.jpg\" alt=\"poker academia\" width=\"\" height=\"0\" loading=\"lazy\" title=\"Academia Poker\"><\/div><p class=\"uagb-ifb-desc\">Consta de una combinaci\u00f3n de cuatro cartas del mismo valor y una diferente.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-2f17c129 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top fondo-blanco sombra-caja\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><span class=\"ez-toc-section\" id=\"Full\"><\/span>Full<span class=\"ez-toc-section-end\"><\/span><\/h3><\/div><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/full-academia-poker.jpg\" alt=\"full academia poker\" width=\"\" height=\"0\" loading=\"lazy\" title=\"Academia Poker\"><\/div><p class=\"uagb-ifb-desc\">Es una combinaci\u00f3n de tres cartas del mismo valor y un par.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-aab76b48 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top fondo-blanco sombra-caja\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><span class=\"ez-toc-section\" id=\"Color\"><\/span>Color<span class=\"ez-toc-section-end\"><\/span><\/h3><\/div><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/color-academia-poker.jpg\" alt=\"color academia poker\" width=\"\" height=\"0\" loading=\"lazy\" title=\"Academia Poker\"><\/div><p class=\"uagb-ifb-desc\">Es una combinaci\u00f3n de cinco cartas en secuencia de diferentes palos.z<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-2422c0df uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top fondo-blanco sombra-caja\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><span class=\"ez-toc-section\" id=\"Escalera\"><\/span>Escalera<span class=\"ez-toc-section-end\"><\/span><\/h3><\/div><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/escalera-academia-poker.jpg\" alt=\"escalera academia poker\" width=\"\" height=\"0\" loading=\"lazy\" title=\"Academia Poker\"><\/div><p class=\"uagb-ifb-desc\">Es una combinaci\u00f3n de cinco cartas en secuencia de diferentes palos.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-8005015a uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top fondo-blanco sombra-caja\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><span class=\"ez-toc-section\" id=\"Tercia\"><\/span>Tercia<span class=\"ez-toc-section-end\"><\/span><\/h3><\/div><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/tercia-academia-poker.jpg\" alt=\"tercia academia poker\" width=\"\" height=\"0\" loading=\"lazy\" title=\"Academia Poker\"><\/div><p class=\"uagb-ifb-desc\">Se compone de tres cartas del mismo valor y dos diferentes.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-aab93917 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top fondo-blanco sombra-caja\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><span class=\"ez-toc-section\" id=\"Doble-Pareja\"><\/span>Doble Pareja<span class=\"ez-toc-section-end\"><\/span><\/h3><\/div><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/doble-pareja-academia-poker.jpg\" alt=\"doble pareja academia poker\" width=\"\" height=\"0\" loading=\"lazy\" title=\"Academia Poker\"><\/div><p class=\"uagb-ifb-desc\">Est\u00e1 formada, como su nombre lo indica, por dos parejas y una carta diferente.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-439357e6 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top fondo-blanco sombra-caja\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><span class=\"ez-toc-section\" id=\"Pareja\"><\/span>Pareja<span class=\"ez-toc-section-end\"><\/span><\/h3><\/div><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/pareja-academia-poker.jpg\" alt=\"pareja academia poker\" width=\"\" height=\"0\" loading=\"lazy\" title=\"Academia Poker\"><\/div><p class=\"uagb-ifb-desc\">Es una de las combinaciones m\u00e1s f\u00e1ciles de formar. Dos cartas son iguales y tres son diferentes. <\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-ad9b814c uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top fondo-blanco sombra-caja\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><span class=\"ez-toc-section\" id=\"Carta-Mas-Alta\"><\/span>Carta M\u00e1s Alta<span class=\"ez-toc-section-end\"><\/span><\/h3><\/div><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/carta-alta-academia-poker.jpg\" alt=\"carta alta academia poker\" width=\"\" height=\"0\" loading=\"lazy\" title=\"Academia Poker\"><\/div><p class=\"uagb-ifb-desc\">La carta m\u00e1s alta define qui\u00e9n es el ganador de la ronda en caso de que los jugadores no formen ninguna de las combinaciones mencionadas anteriormente.<\/p><\/div><\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Orden-de-manos-de-poker-%E2%80%9CAce-to-Five%E2%80%9D-California\"><\/span>Orden de manos de p\u00f3ker &#8220;Ace to Five&#8221; (California)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">En las combinaciones de p\u00f3ker Ace to Five, tambi\u00e9n conocidas como California, los palos no tienen valor y los ases siempre se consideran cartas bajas. Por tanto, las Escaleras y los Colores no tienen valor en este ranking de manos. <\/p>\n\n<p class=\"wp-block-paragraph\">Este ranking de manos se aplica solo en las siguientes modalidades de p\u00f3ker:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/academiapoker.net\/es-cl\/tipos-poker\/como-jugar-omaha-hi-lo\/\">Omaha Hi\/Lo<\/a>: el valor del bote se divide entre la mano m\u00e1s alta (<em>High<\/em>) y la mano m\u00e1s baja (<em>Low<\/em>). La opci\u00f3n <em>8 or Better<\/em> est\u00e1 disponible en esta modalidad y significa que para que una mano sea considerada <em>Low<\/em>, debe estar formada por valores por debajo de ocho. <\/li>\n\n\n\n<li><a href=\"https:\/\/academiapoker.net\/es-cl\/tipos-poker\/como-jugar-razz\/\">Razz<\/a>: tambi\u00e9n conocida como Seven Card Stud Low, aqu\u00ed los jugadores reciben siete cartas en la mano y deben formar la mejor mano <em>Low<\/em> para ganar el bote. <em>8 or Better<\/em> no est\u00e1 disponible en esta modalidad, ya que solo est\u00e1 en juego el sistema <em>Low<\/em>.<\/li>\n\n\n\n<li>Stud Hi\/Lo: en Seven Card Stud Hi\/Lo, el bote se divide para obtener la mejor mano <em>High<\/em> y la mejor mano <em>Low<\/em> utilizando el sistema de <em>8 or Better<\/em>. Si no hay una mano <em>Low<\/em> que califique, todo el bote va al ganador de la mano \u201c<em>High<\/em>\u201d. <\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Five-Low-o-Wheels\"><\/span><em>Five Low<\/em> (o <em>Wheels<\/em>)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"350\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/five-low-manos-poker.jpg\" alt=\"five low manos poker\" class=\"wp-image-784\" title=\"Five Low (o Wheels)\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/five-low-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/five-low-manos-poker-300x131.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/five-low-manos-poker-768x336.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Esta secuencia est\u00e1 formada por los valores 5, 4, 3, 2 y el As. En caso de empate, el bote \u201c<em>Low<\/em>\u201d se lo lleva el ganador del \u201c<em>High<\/em>\u201d. <\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Six-Low\"><\/span><em>Six Low<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"355\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/six-low-manos-poker.jpg\" alt=\"six low manos poker\" class=\"wp-image-786\" title=\"Six Low\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/six-low-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/six-low-manos-poker-300x133.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/six-low-manos-poker-768x341.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Cinco cartas de cualquier valor, siendo 6 la m\u00e1s alta. Si hay un empate, la segunda carta m\u00e1s baja gana el bote.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Seven-Low\"><\/span><em>Seven Low<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"357\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/seven-low-manos-poker.jpg\" alt=\"seven low manos poker\" class=\"wp-image-788\" title=\"Seven Low\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/seven-low-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/seven-low-manos-poker-300x134.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/seven-low-manos-poker-768x343.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Mismo sistema que <em>Six Low<\/em>, con la carta 7 siendo la de mayor valor.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Eight-Low\"><\/span><em>Eight Low<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"352\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/eight-low-manos-poker.jpg\" alt=\"eight low manos poker\" class=\"wp-image-789\" title=\"Eight Low\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/eight-low-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/eight-low-manos-poker-300x132.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/eight-low-manos-poker-768x338.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">La carta m\u00e1s alta en esta combinaci\u00f3n es el 8 y el desempate funciona de la misma manera que las combinaciones <em>Six Low<\/em> y <em>Seven Low<\/em>.<\/p>\n\n<p class=\"wp-block-paragraph\">Esta es la mano m\u00e1s baja en el sistema \u201c<em>8 or Better<\/em>\u201d, que es v\u00e1lido en los juegos Omaha Hi\/Lo y Stud Hi\/Lo. En Razz no existe tal l\u00edmite y la mano m\u00e1s baja puede estar formada por un 10 o incluso una Q.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ranking-de-cartas-de-poker-%E2%80%9CDeuce-to-Seven%E2%80%9D-Kansas-City\"><\/span><a><\/a>Ranking de cartas de p\u00f3ker &#8220;Deuce to Seven&#8221; (Kansas City)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">El ranking de manos de Deuce to Seven funciona justo al contrario del <em>High<\/em>. La peor combinaci\u00f3n del <em>High<\/em>, que es el <em>Seven-Five High<\/em> de diferentes palos, es la mejor mano en este ranking. <\/p>\n\n<p class=\"wp-block-paragraph\">Las modalidades de juego de p\u00f3ker que utiliza este sistema de ranking son:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>2-7 Single Draw: este juego es una modalidad de <em>Low Poker<\/em>, donde la mejor mano m\u00e1s baja es la ganadora. En <em>Single Draw<\/em>, los jugadores solo tendr\u00e1n una oportunidad de descartar y obtener nuevas cartas. <\/li>\n\n\n\n<li>2-7 <em>Triple Draw<\/em>: este juego <em>Low<\/em> funciona exactamente igual que el anterior, con la diferencia de que los jugadores pueden cambiar sus cartas tres veces.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">En esta clasificaci\u00f3n de manos, el As es v\u00e1lido como la carta m\u00e1s alta y las Escaleras y Colores son v\u00e1lidos.<\/p>\n\n<p class=\"wp-block-paragraph\">Veamos las mejores secuencias de Poker Deuce to Seven.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Seven-Low-2\"><\/span><em>Seven Low<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"358\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/seven-low-deuces-manos-poker.jpg\" alt=\"seven low deuces manos poker\" class=\"wp-image-790\" title=\"seven low deuces\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/seven-low-deuces-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/seven-low-deuces-manos-poker-300x134.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/seven-low-deuces-manos-poker-768x344.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Mano formada por cinco cartas diferentes, de diferentes palos, siendo la carta de valor 7 la m\u00e1s alta. La mejor mano posible es la <em>Wheel<\/em>, compuesta por 7, 5, 4, 3, 2, y en caso de empate, la segunda carta m\u00e1s baja gana un bote. <\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Eight-Low-2\"><\/span><em>Eight Low<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"352\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/eight-low-deuces-manos-poker.jpg\" alt=\"eight low deuces manos poker\" class=\"wp-image-792\" title=\"eight low deuces\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/eight-low-deuces-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/eight-low-deuces-manos-poker-300x132.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/eight-low-deuces-manos-poker-768x338.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Funciona de la misma manera que la combinaci\u00f3n anterior, pero en lugar de 7, la carta m\u00e1s alta es 8. El sistema de desempate anterior tambi\u00e9n se aplica aqu\u00ed. <\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Nine-Low\"><\/span><em>Nine Low<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"356\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/nine-low-deuces-manos-poker.jpg\" alt=\"nine low deuces manos poker\" class=\"wp-image-793\" title=\"nine low deuces\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/nine-low-deuces-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/nine-low-deuces-manos-poker-300x134.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/nine-low-deuces-manos-poker-768x342.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed, la carta 9 es la m\u00e1s alta, form\u00e1ndose con otras cuatro cartas de diferentes valores y palos menores a 9.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ten-Low\"><\/span><em>Ten Low<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/ten-low-deuces-manos-poker.jpg\" alt=\"ten low deuces manos poker\" class=\"wp-image-794\" title=\"ten low deuces\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/ten-low-deuces-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/ten-low-deuces-manos-poker-300x200.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/ten-low-deuces-manos-poker-768x513.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Funciona igual que las combinaciones anteriores, con la carta de mayor valor siendo 10.<\/p>\n\n<p class=\"wp-block-paragraph\">En Deuces to Seven no hay un l\u00edmite como <em>8 Or Better<\/em>, la combinaci\u00f3n m\u00e1s baja siempre ser\u00e1 la ganadora.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Puntuacion-de-manos-de-poker-%E2%80%9CBadugi%E2%80%9D\"><\/span><a><\/a>Puntuaci\u00f3n de manos de p\u00f3ker &#8220;Badugi&#8221;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">El sistema Badugi funciona de manera diferente a los tradicionales. En Badugi se usa una combinaci\u00f3n de cuatro cartas y cada carta debe ser de un palo diferente. El As, como en Ace to Five, se considera una carta baja.  <\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Badugi\"><\/span><em>Badugi<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/badugi-manos-poker.jpg\" alt=\"badugi manos poker\" class=\"wp-image-795\" title=\"Badugi manos\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/badugi-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/badugi-manos-poker-300x176.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/badugi-manos-poker-768x451.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Es la combinaci\u00f3n de cuatro cartas diferentes, sin parejas y de diferentes palos.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Three-Card-Hand\"><\/span><em>Three-Card Hand<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"477\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/three-card-manos-poker.jpg\" alt=\"three card manos poker\" class=\"wp-image-797\" title=\"three card\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/three-card-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/three-card-manos-poker-300x179.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/three-card-manos-poker-768x458.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">En esta mano, solo tres cartas son v\u00e1lidas, porque una de ellas est\u00e1 emparejada o es del mismo palo que otra carta. Entre las dos, la carta m\u00e1s baja es la que juega. <\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Two-Card-Hand\"><\/span><em>Two-Card Hand<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"482\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/two-cards-manos-poker.jpg\" alt=\"two cards manos poker\" class=\"wp-image-798\" title=\"two cards\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/two-cards-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/two-cards-manos-poker-300x181.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/two-cards-manos-poker-768x463.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Se compone de dos cartas sin pareja y de palos diferentes. Las cartas no emparejadas m\u00e1s bajas son las que entran al juego. <\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"One-Card-Hand\"><\/span><em>One-Card Hand<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"476\" src=\"https:\/\/academiapoker.net\/wp-content\/uploads\/one-card-manos-poker.jpg\" alt=\"one card manos poker\" class=\"wp-image-799\" title=\"one card\" srcset=\"https:\/\/academiapoker.net\/wp-content\/uploads\/one-card-manos-poker.jpg 800w, https:\/\/academiapoker.net\/wp-content\/uploads\/one-card-manos-poker-300x179.jpg 300w, https:\/\/academiapoker.net\/wp-content\/uploads\/one-card-manos-poker-768x457.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Combinaci\u00f3n formada por una sola carta disponible para el juego. Por ejemplo, si las cuatro cartas son del mismo palo, solo la carta m\u00e1s baja entrar\u00e1 al juego. <\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCuales-son-las-mejores-manos-de-poker\"><\/span><a><\/a>\u00bfCu\u00e1les son las mejores manos de p\u00f3ker?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">En el p\u00f3ker, uno de los consejos m\u00e1s importantes a seguir es no entrar en todas las manos. Debes ser selectivo. Para ello, es importante conocer el <a href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/manos-poker\/\">ranking de las mejores manos de p\u00f3ker<\/a>, lo cual te ayudar\u00e1 a saber cu\u00e1ndo jugar con todo y cu\u00e1ndo retirarte.  <\/p>\n\n<p class=\"wp-block-paragraph\">Entonces, conozcamos las combinaciones de mejores manos:<\/p>\n\n<p class=\"wp-block-paragraph\">Debemos considerar las posiciones en la mesa, que tambi\u00e9n influyen en el resultado. Pero las primeras cinco combinaciones se consideran Premium, y debes invertir en ellas, independientemente de la posici\u00f3n en la mesa. <\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Nombres-populares-de-manos-de-poker\"><\/span><a><\/a>Nombres populares de manos de p\u00f3ker<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">As\u00ed como todos los deportes tienen una jerga popular, el juego del p\u00f3ker no pod\u00eda quedarse afuera. Conozcamos <a href=\"https:\/\/academiapoker.net\/es-cl\/escuela\/apodos-manos-poker\/\">los apodos m\u00e1s populares para este famoso deporte de la mente<\/a>. <\/p>\n\n<ol class=\"wp-block-list\">\n<li>AA<\/li>\n\n\n\n<li>KK<\/li>\n\n\n\n<li>QQ<\/li>\n\n\n\n<li>AK (mismo palo)<\/li>\n\n\n\n<li>JJ<\/li>\n\n\n\n<li>1010<\/li>\n\n\n\n<li>AQ (mismo palo)<\/li>\n\n\n\n<li>AJ (mismo palo)<\/li>\n\n\n\n<li>AK (palos diferentes)<\/li>\n\n\n\n<li>KQ (mismo palo)<\/li>\n\n\n\n<li>A10 (mismo palo)<\/li>\n\n\n\n<li>KJ (mismo palo)<\/li>\n\n\n\n<li>AQ (palos diferentes)<\/li>\n\n\n\n<li>99<\/li>\n\n\n\n<li>JQ (mismo palo)<\/li>\n<\/ol>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"TNT-o-TT\"><\/span><a><\/a>TNT (o TT)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Nombre que se le da al par de dieces.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Maverick\"><\/span><a><\/a>Maverick<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Nombre en honor a la m\u00fasica de la serie que menciona las cartas Q y J.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ronaldo\"><\/span><a><\/a>Ronaldo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Referente a las cartas 9 (usado solo en Brasil).<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Rockets\"><\/span><a><\/a>Rockets<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Es el nombre que se le da al par de AA.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Gutshot\"><\/span><a><\/a><em>Gutshot<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Es la carta que falta para formar una escalera. Por ejemplo, 10 y As y la mesa tiene J y K, entonces necesitas la dama (Q). <\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Kojak\"><\/span><a><\/a>Kojak<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Nombre dado en honor a un antiguo detective de la televisi\u00f3n estadounidense, y est\u00e1 formada por la combinaci\u00f3n de K y J.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wheel\"><\/span><a><\/a><em>Wheel<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Nombre dado a la menor mano de Escalera posible.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Backdoor\"><\/span><a><\/a><em>Backdoor<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Expresi\u00f3n utilizada para expresar la falta de dos cartas para formar una mano.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Valentines\"><\/span><a><\/a><em>Valentines<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">En referencia al D\u00eda de San Valent\u00edn, este nombre se le dio a la combinaci\u00f3n de K y Q de corazones.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Munecos-de-Nieve\"><\/span><a><\/a>Mu\u00f1ecos de Nieve<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Formado por pares de ochos y el nombre se debe a la forma del n\u00famero ocho.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Jacks\"><\/span><a><\/a>Jacks<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Formado por un par de sotas.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Phil-Hellmuth\"><\/span><a><\/a>Phil Hellmuth<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">El jugador Hellmuth gan\u00f3 el torneo WSOP en 1989 con un par de nueves negros.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Dead-Mans-Hand\"><\/span><a><\/a><em>Dead Man&#8217;s Hand<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Combinaci\u00f3n formada por un 8 y un As. El nombre se debe a la muerte del famoso vaquero Wild Bill, quien fue asesinado con esta combinaci\u00f3n en la mano. <\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"King-Kong\"><\/span><a><\/a>King Kong<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Est\u00e1 formada por una pareja de reyes (K).<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Open-Ended\"><\/span><a><\/a><em>Open Ended<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Mano formada por una combinaci\u00f3n incompleta de Escalera abierta en ambos extremos.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Doyle-Brunson\"><\/span><a><\/a>Doyle Brunson<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Esta mano consta de un 10 y un 2, y el nombre se debe a que el jugador Doyle Brunson gan\u00f3 dos t\u00edtulos mundiales con esta mano.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Big-Slick\"><\/span><a><\/a><em>Big Slick<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Es la mejor mano sin ser un par, o sea, AK.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo-es-el-desempate-en-el-poker\"><\/span><a><\/a>\u00bfC\u00f3mo es el desempate en el p\u00f3ker?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">La forma m\u00e1s popular de desempate es con el <em>Kicker<\/em>. Este es la carta extra, que no forma parte de la combinaci\u00f3n de cinco cartas, y que se utiliza para el desempate. La carta extra m\u00e1s alta es la ganadora.  <\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span><a><\/a>Conclusi\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">Conocer todas las combinaciones de manos posibles en todas las <a href=\"https:\/\/academiapoker.net\/es-cl\/tipos-poker\/\">modalidades de p\u00f3ker<\/a> es importante para saber cu\u00e1ndo entrar a una mesa y arriesgar\u2026 y cu\u00e1ndo retirarse.<\/p>\n\n<p class=\"wp-block-paragraph\">Tener en cuenta las mejores manos te ayudar\u00e1 a decidir tu pr\u00f3ximo paso. Presta atenci\u00f3n a esto para evitar grandes p\u00e9rdidas e invertir solo en manos que tengan m\u00e1s probabilidades de ganancias. <\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Preguntas-relacionadas\"><\/span><a><\/a>Preguntas relacionadas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">Los jugadores principiantes pueden tener muchas preguntas o dudas relacionadas con el juego cuando comienzan a jugar.<\/p>\n\n<p class=\"wp-block-paragraph\">Algunas de ellas solo se responden con mucha pr\u00e1ctica, como, por ejemplo, saber cu\u00e1ndo tu oponente est\u00e1 haciendo un farol.<\/p>\n\n<p class=\"wp-block-paragraph\">Otras dudas son m\u00e1s b\u00e1sicas, relacionadas con las estrategias, que veremos ahora.<\/p>\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1670963063389\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%C2%BFCual-es-la-mano-mas-fuerte-en-el-poker\"><\/span>\u00bfCu\u00e1l es la mano m\u00e1s fuerte en el p\u00f3ker?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Como vimos anteriormente, la mano m\u00e1s fuerte es la Escalera Real, formada por la secuencia A, K, Q, J y 10, todas del mismo palo. Dado que la probabilidad de que salga esta mano es baja, la mano Escalera de Color tambi\u00e9n es muy fuerte y con mayores probabilidades. <\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1670963072641\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%C2%BFQue-palo-vale-mas-en-el-poker\"><\/span>\u00bfQu\u00e9 palo vale m\u00e1s en el p\u00f3ker?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>En el p\u00f3ker, los cuatro palos del juego tienen el mismo valor, no hay ning\u00fan palo mejor que el otro. La carta m\u00e1s alta es el as, formando as\u00ed con otro as, la mano m\u00e1s fuerte que un jugador puede tener en la mano antes de las cartas comunitarias, siempre que estemos hablando de Texas Holdem Poker. <\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1675379523574\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%C2%BFCual-es-la-mano-mas-debil-en-el-poker\"><\/span>\u00bfCu\u00e1l es la mano m\u00e1s d\u00e9bil en el p\u00f3ker?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Considerando una situaci\u00f3n pre-flop en Texas Holdem, que es la m\u00e1s popular, la mano m\u00e1s d\u00e9bil que un jugador puede recibir en sus cartas ocultas es un 7-2 de diferentes palos.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1675379534521\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%C2%BFPor-que-dar-a-las-manos-de-poker-nombres-especiales-o-%E2%80%9Capodos%E2%80%9D\"><\/span>\u00bfPor qu\u00e9 dar a las manos de p\u00f3ker nombres especiales o &#8220;apodos&#8221;?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>La pr\u00e1ctica ha evolucionado espont\u00e1neamente, y cada apodo para una mano de p\u00f3ker puede tener un origen diferente. En general, cuando se trata de comentar una mano de p\u00f3ker, es m\u00e1s r\u00e1pido y f\u00e1cil visualizar una mano por su apodo que describiendo exhaustivamente los n\u00fameros y palos implicados. Por supuesto, para que la comunicaci\u00f3n fluya, estos apodos deben conocerse.  <\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":" ","protected":false},"author":1,"featured_media":2323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela"],"uagb_featured_image_src":{"full":["https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker-academia.jpg",371,247,false],"thumbnail":["https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker-academia.jpg",150,100,false],"medium":["https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker-academia.jpg",300,200,false],"medium_large":["https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker-academia.jpg",371,247,false],"large":["https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker-academia.jpg",371,247,false],"1536x1536":["https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker-academia.jpg",371,247,false],"2048x2048":["https:\/\/academiapoker.net\/wp-content\/uploads\/secuencia-manos-poker-academia.jpg",371,247,false]},"uagb_author_info":{"display_name":"academiapokernet","author_link":"https:\/\/academiapoker.net\/es-cl\/author\/academiapokernet\/"},"uagb_comment_info":0,"uagb_excerpt":"[&hellip;]","_links":{"self":[{"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/posts\/2322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/comments?post=2322"}],"version-history":[{"count":3,"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/posts\/2322\/revisions"}],"predecessor-version":[{"id":5119,"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/posts\/2322\/revisions\/5119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/media\/2323"}],"wp:attachment":[{"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/media?parent=2322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/categories?post=2322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/academiapoker.net\/es-cl\/wp-json\/wp\/v2\/tags?post=2322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}